{"id":520,"date":"2016-04-04T21:44:32","date_gmt":"2016-04-04T20:44:32","guid":{"rendered":"https:\/\/blateman-bobine.com\/fr\/?p=520"},"modified":"2025-03-28T11:18:44","modified_gmt":"2025-03-28T10:18:44","slug":"blateman-et-bobine-en-dedicatoria-en-la-ferte-sous-jouarre-77-9-y-10-abril-2016","status":"publish","type":"post","link":"https:\/\/blateman-bobine.com\/es\/blateman-et-bobine-en-dedicatoria-en-la-ferte-sous-jouarre-77-9-y-10-abril-2016\/","title":{"rendered":"Blateman y Bobine firman en La Fert\u00e9-sous-Jouarre los d\u00edas 9 y 10 de abril de 2016"},"content":{"rendered":"<p class=\"has-text-align-left wp-block-paragraph\">Venga a vernos al <a title=\"Salon univers BD de la Fert\u00e9 sous Jouarre\" href=\"http:\/\/mediatheque.fertesousjouarre.net\/fertesousjouarre.net\/cms\/articleview\/id\/85\" target=\"_blank\">Sal\u00f3n Univers BD de la Fert\u00e9-sous-Jouarre<\/a> (Mediateca Samuel Beckett) cerca de Par\u00eds.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">En<strong> 9 y 10 de abril<\/strong> pr\u00f3ximamente.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Adem\u00e1s, el<strong> tema del espect\u00e1culo es \"superh\u00e9roes<\/strong>si no es<strong> perfecto para Blateman y Bobine, <\/strong>\u00a1Esto!<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i0.wp.com\/storage.canalblog.com\/46\/25\/925464\/109920715_o.jpg\" target=\"_blank\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/storage.canalblog.com\/46\/25\/925464\/109920715.jpg\" alt=\"BD_ferte_blateman_bobine\"\/><\/a><\/figure>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Vhenin<\/strong> <strong>Cartera:<\/strong> <a href=\"http:\/\/www.vhenin.be\/\" target=\"_blank\">www.vhenin.be<\/a>&nbsp;y <a href=\"http:\/\/www.vincent-henin.be\/\" target=\"_blank\">www.vincent-henin.be<br>\n<\/a><strong>Facebook:<\/strong> <a href=\"https:\/\/fr-fr.facebook.com\/vincenthenin.comixillustration\" target=\"_blank\">Vincent Henin Comix Ilustraci\u00f3n (Vhenin)<br>\n<\/a><strong>El blog de Vhenin:<\/strong> <a href=\"http:\/\/www.vhenin.canalblog.com\" target=\"_blank\">www.vhenin.canalblog.com<\/a><br>\n<strong>YouTube: <\/strong><a title=\"Canal YouTube de Vhenin\" href=\"https:\/\/www.youtube.com\/channel\/UCFgRf_TU8ES5LJNMaKOr8Eg\" target=\"_blank\">La gama Vhenin <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Venez nous&nbsp;rencontrer lors du Salon Univers BD de la Fert\u00e9-sous-Jouarre (m\u00e9diath\u00e8que Samuel Beckett) pr\u00e8s de Paris! Les 9 et 10 avril prochains. En plus, le th\u00e8me du salon est &lsquo;super-h\u00e9ros&lsquo;, si c&rsquo;est pas parfait pour Blateman et Bobine, \u00e7a..! Vhenin Portfolio: <a href=\"http:\/\/www.vhenin.be&nbsp;et\" rel=\"nofollow\">http:\/\/www.vhenin.be&nbsp;et<\/a> <a href=\"http:\/\/www.vincent-henin.be\" rel=\"nofollow\">http:\/\/www.vincent-henin.be<\/a> Facebook: Vincent Henin Comix Illustration (Vhenin) Le Blog de Vhenin: <a href=\"http:\/\/www.vhenin.canalblog.com\" rel=\"nofollow\">http:\/\/www.vhenin.canalblog.com<\/a> YouTube: [&hellip;]<\/p>\n","protected":false},"author":74241772,"featured_media":1835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1223035],"tags":[44670,21752,263100701,1338044,346062291,39123,3968362,1536666,299480777],"class_list":["post-520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dedicaces","tag-bande-dessinee","tag-bd","tag-blateman","tag-bobine","tag-loindetout","tag-super-heros","tag-tarek","tag-tartamudo","tag-vhenin"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2016\/04\/image-1.png?fit=1024%2C768&ssl=1","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4LVhx-8o","jetpack-related-posts":[{"id":1927,"url":"https:\/\/blateman-bobine.com\/es\/blateman-bobine-en-dedicatoria-en-tournai-12-y-13-de-abril-de-2025\/","url_meta":{"origin":520,"position":0},"title":"Blateman &amp; Bobine firman en Tournai - 12 y 13 de abril de 2025","author":"Vhenin","date":"10 abril 2025","format":false,"excerpt":"Venga a verme al Festival de Tournai les Bulles el s\u00e1bado y domingo 12 y 13 de abril de 2025.M\u00e1s informaci\u00f3n en: https:\/\/opalebd.com\/festivals\/details\/2239","rel":"","context":"En \u00abD\u00e9dicaces\u00bb","block_context":{"text":"D\u00e9dicaces","link":"https:\/\/blateman-bobine.com\/es\/categoria\/dedicatorias\/"},"img":{"alt_text":"Blateman & Bobine - festival-BD-Tournai","src":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2025\/04\/001_2025_gf.jpg?fit=500%2C701&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":797,"url":"https:\/\/blateman-bobine.com\/es\/salon-bd-de-bulleberry-2016\/","url_meta":{"origin":520,"position":1},"title":"Salon BD de BulleBerry 2016","author":"","date":"4 octubre 2016","format":false,"excerpt":"\u2605\u2605\u2605 Tarek en d\u00e9dicace au salon BD de BulleBerry \u00e0 Bourges du 1er au 2 oct. \u2605\u2605\u2605 Le tapis de souris Blateman et Bobine est dor\u00e9navant disponible \u00e0 la vente au prix de 10 euros !","rel":"","context":"En \u00abD\u00e9dicaces\u00bb","block_context":{"text":"D\u00e9dicaces","link":"https:\/\/blateman-bobine.com\/es\/categoria\/dedicatorias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2016\/10\/p1450071.jpg?fit=1024%2C684&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2016\/10\/p1450071.jpg?fit=1024%2C684&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2016\/10\/p1450071.jpg?fit=1024%2C684&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2016\/10\/p1450071.jpg?fit=1024%2C684&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3385,"url":"https:\/\/blateman-bobine.com\/es\/blateman-en-dedicace-avec-brad-pitt-a-tournai-les-bulles-b-11-et-12-avril-2026\/","url_meta":{"origin":520,"position":2},"title":"Blateman en d\u00e9dicace avec Brad Pitt \u00e0 Tournai-les-Bulles (B) &#8211; 11 et 12 avril 2026","author":"Vhenin","date":"9 abril 2026","format":false,"excerpt":"Brad Pitt en d\u00e9dicaces avec Blateman & Bobine \u00e0 Tournai-les-Bulles (Festival International de BD), Belgique, 11 et 12 avril 2026","rel":"","context":"En \u00abAround Blateman\u00bb","block_context":{"text":"Around Blateman","link":"https:\/\/blateman-bobine.com\/es\/categoria\/alrededor-de-blateman\/"},"img":{"alt_text":"Brad Pitt, fan de Blateman & Bobine, s\u00e9rie de BD franco-belge","src":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2026\/04\/Brad-Pitt-at-comic-convention-horizontal-WEB.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2026\/04\/Brad-Pitt-at-comic-convention-horizontal-WEB.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2026\/04\/Brad-Pitt-at-comic-convention-horizontal-WEB.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2026\/04\/Brad-Pitt-at-comic-convention-horizontal-WEB.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2026\/04\/Brad-Pitt-at-comic-convention-horizontal-WEB.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3325,"url":"https:\/\/blateman-bobine.com\/es\/blateman-bobine-emerveillent-a-verlaine\/","url_meta":{"origin":520,"position":3},"title":"Blateman &#038; Bobine \u00e9merveillent \u00e0 Verlaine","author":"Vhenin","date":"5 marzo 2026","format":false,"excerpt":"Blateman & Bobine \u00e9taient pr\u00e9sents \u00e0 la F\u00eate de la B.D. et du Livre Jeunesse de Verlaine le 8 f\u00e9vrier. L\u2019\u00e9v\u00e9nement a offert un accueil exceptionnel, avec une organisation impeccable et une ambiance chaleureuse. Une journ\u00e9e au top pour nos super-h\u00e9ros\u2026 ou plut\u00f4t super-z\u00e9ros !","rel":"","context":"En \u00abD\u00e9dicaces\u00bb","block_context":{"text":"D\u00e9dicaces","link":"https:\/\/blateman-bobine.com\/es\/categoria\/dedicatorias\/"},"img":{"alt_text":"Blateman & Bobine - Fete de la BD et du livre jeunesse - Verlaine 2026","src":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2026\/03\/IMG_20260208_112256_Bokeh-WEB.jpg?fit=800%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2026\/03\/IMG_20260208_112256_Bokeh-WEB.jpg?fit=800%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2026\/03\/IMG_20260208_112256_Bokeh-WEB.jpg?fit=800%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2026\/03\/IMG_20260208_112256_Bokeh-WEB.jpg?fit=800%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":870,"url":"https:\/\/blateman-bobine.com\/es\/blateman-bobine-firmara-en-el-salon-sobd-de-paris-el-3-de-diciembre-de-2016\/","url_meta":{"origin":520,"position":4},"title":"Blateman &amp; Bobine firman en Par\u00eds - Sal\u00f3n SoBD - 3 de diciembre de 2016","author":"Vhenin","date":"28 noviembre 2016","format":false,"excerpt":"Hello! Le dessinateur Vhenin sera pr\u00e9sent toute la journ\u00e9e du samedi 3 d\u00e9cembre 2016 pour signer et d\u00e9dicacer sa BD \"Blateman & Bobine\" au stand Tartamudo. Salon SoBD - La BD au coeur de Paris Halle des Blancs-Manteaux, Paris IVe 48 rue Vieille-du-Temple, entr\u00e9e libre Vhenin Portfolio: www.vhenin.be Facebook: Vincent\u2026","rel":"","context":"En \u00abD\u00e9dicaces\u00bb","block_context":{"text":"D\u00e9dicaces","link":"https:\/\/blateman-bobine.com\/es\/categoria\/dedicatorias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2016\/11\/affiche-sobdjpg.jpg?fit=728%2C1030&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2016\/11\/affiche-sobdjpg.jpg?fit=728%2C1030&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2016\/11\/affiche-sobdjpg.jpg?fit=728%2C1030&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2016\/11\/affiche-sobdjpg.jpg?fit=728%2C1030&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1869,"url":"https:\/\/blateman-bobine.com\/es\/blateman-reel-in-dedication-in-bruges-30-de-marzo-de-2025\/","url_meta":{"origin":520,"position":5},"title":"Blateman &amp; Bobine firman en Brujas - 30 de marzo de 2025","author":"Vhenin","date":"28 marzo 2025","format":false,"excerpt":"Ven a verme al Festival del C\u00f3mic de Brujas (Stripbeurs \/ Stripfestival Brugge) el domingo 30 de marzo de 2025.M\u00e1s informaci\u00f3n en: https:\/\/www.facebook.com\/bruggestripfestival\/about","rel":"","context":"En \u00abD\u00e9dicaces\u00bb","block_context":{"text":"D\u00e9dicaces","link":"https:\/\/blateman-bobine.com\/es\/categoria\/dedicatorias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2024\/12\/dedi-bb-03.jpg?fit=666%2C1000&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2024\/12\/dedi-bb-03.jpg?fit=666%2C1000&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blateman-bobine.com\/wp-content\/uploads\/2024\/12\/dedi-bb-03.jpg?fit=666%2C1000&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blateman-bobine.com\/es\/wp-json\/wp\/v2\/posts\/520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blateman-bobine.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blateman-bobine.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blateman-bobine.com\/es\/wp-json\/wp\/v2\/users\/74241772"}],"replies":[{"embeddable":true,"href":"https:\/\/blateman-bobine.com\/es\/wp-json\/wp\/v2\/comments?post=520"}],"version-history":[{"count":8,"href":"https:\/\/blateman-bobine.com\/es\/wp-json\/wp\/v2\/posts\/520\/revisions"}],"predecessor-version":[{"id":1836,"href":"https:\/\/blateman-bobine.com\/es\/wp-json\/wp\/v2\/posts\/520\/revisions\/1836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blateman-bobine.com\/es\/wp-json\/wp\/v2\/media\/1835"}],"wp:attachment":[{"href":"https:\/\/blateman-bobine.com\/es\/wp-json\/wp\/v2\/media?parent=520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blateman-bobine.com\/es\/wp-json\/wp\/v2\/categories?post=520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blateman-bobine.com\/es\/wp-json\/wp\/v2\/tags?post=520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}